{"id":8,"date":"2015-10-21T08:57:04","date_gmt":"2015-10-21T06:57:04","guid":{"rendered":"https:\/\/weingut-kaufmann-ziegler.de\/catalog\/?page_id=8"},"modified":"2025-07-16T11:56:15","modified_gmt":"2025-07-16T09:56:15","slug":"agb","status":"publish","type":"page","link":"https:\/\/weingut-kaufmann-ziegler.de\/catalog\/agb\/","title":{"rendered":"AGB \/ Impressum"},"content":{"rendered":"<p><!-- IBGHTML --><\/p>\n<p>IMPRESSUM<\/p>\n<p>Weingut Kaufmann-Ziegler<br \/>\nInhaber: Walter Ziegler<br \/>\nRhodter Str. 6 + Josef-Meyer-Str. 4<br \/>\n76835 Weyher<br \/>\nTel: 06323\/3255 Fax:06323\/949045<br \/>\nE-Mail: <a href=\"mailto:info@weingut-kaufmann-ziegler.de\">info@weingut-kaufmann-ziegler.de<\/a><br \/>\nSteuernr: 24\/232\/00322 Finanzamt Landau i. d. Pfalz<\/p>\n<p>Unsere Aufsichtsbeh\u00f6rde ist:<br \/>\nMinisterium f\u00fcr Umwelt, Landwirtschaft, Ern\u00e4hrung, Weinbau und Forsten, Kaiser-Friedrich-Str. 1, 55116 Mainz.<\/p>\n<p>Wir geh\u00f6ren der Landwirtschaftskammer Rheinland-Pfalz, Rheinland-Pfalz, Burgenlandstr. 7, 55543 Bad Kreuznach an.<\/p>\n<p>Gesetzliche Grundlage unserer T\u00e4tigkeit: Weingesetz (WeinG)<\/p>\n<p>Inhaltlich verantwortlich gem\u00e4\u00df \u00a76 MDStV: Walter Ziegler<\/p>\n<p><strong>Allgemeine Gesch\u00e4ftsbedingungen<\/strong><\/p>\n<p><strong>1.\u00a0Geltungsbereich<\/strong><\/p>\n<p>F\u00fcr alle Bestellungen \u00fcber unseren Online-Shop gelten die nachfolgenden AGB. Unser Online-Shop richtet sich ausschlie\u00dflich an Verbraucher.<\/p>\n<p>Verbraucher ist jede nat\u00fcrliche Person, die ein Rechtsgesch\u00e4ft zu Zwecken abschlie\u00dft, die \u00fcberwiegend weder ihrer gewerblichen noch ihrer selbst\u00e4ndigen beruflichen T\u00e4tigkeit zugerechnet werden k\u00f6nnen. Unternehmer ist eine nat\u00fcrliche oder juristische Person oder eine rechtsf\u00e4hige Personengesellschaft, die bei Abschluss eines Rechtsgesch\u00e4fts in Aus\u00fcbung ihrer gewerblichen oder selbst\u00e4ndigen beruflichen T\u00e4tigkeit handelt.<\/p>\n<p><strong>2.\u00a0Vertragspartner, Vertragsschluss, Korrekturm\u00f6glichkeiten<\/strong><\/p>\n<p>Der Kaufvertrag kommt zustande mit<\/p>\n<p>Familienweingut Kaufmann-Ziegler<br \/>\nInhaber: Walter Ziegler<br \/>\nRhodter Str. 6 + Josef-Meyer-Str. 4<br \/>\n76835 Weyher<br \/>\nTel: 06323\/3255 Fax:06323\/949045<br \/>\nE-Mail: info@weingut-kaufmann-ziegler.de<br \/>\ninfo@weingut-kaufmann-ziegler.de<\/p>\n<p>Mit Einstellung der Produkte in den Online-Shop geben wir ein verbindliches Angebot zum Vertragsschluss \u00fcber diese Artikel ab. Sie k\u00f6nnen unsere Produkte zun\u00e4chst unverbindlich in den Warenkorb legen und Ihre Eingaben vor Absenden Ihrer verbindlichen Bestellung jederzeit korrigieren, indem Sie die hierf\u00fcr im Bestellablauf vorgesehenen und erl\u00e4uterten Korrekturhilfen nutzen. Der Vertrag kommt zustande, indem Sie durch Anklicken des Bestellbuttons das Angebot \u00fcber die im Warenkorb enthaltenen Waren annehmen. Unmittelbar nach dem Absenden der Bestellung erhalten Sie noch einmal eine Best\u00e4tigung per E-Mail.<\/p>\n<p><strong>3.\u00a0Vertragssprache, Vertragstextspeicherung<\/strong><\/p>\n<p>Die f\u00fcr den Vertragsschluss zur Verf\u00fcgung stehende Sprache ist Deutsch.<\/p>\n<p>Wir speichern den Vertragstext und senden Ihnen die Bestelldaten und unsere AGB in Textform zu. Der Vertragstext ist aus Sicherheitsgr\u00fcnden nicht mehr \u00fcber das Internet zug\u00e4nglich.<\/p>\n<p><strong>4.\u00a0Eigentumsvorbehalt<\/strong><\/p>\n<p>Die Ware bleibt bis zur vollst\u00e4ndigen Bezahlung unser Eigentum.<\/p>\n<p><strong>5.\u00a0Gew\u00e4hrleistung und Garantien<\/strong><\/p>\n<p>Es gilt das gesetzliche M\u00e4ngelhaftungsrecht. Informationen zu gegebenenfalls geltenden zus\u00e4tzlichen Garantien und deren genaue Bedingungen finden Sie jeweils beim Produkt und auf besonderen Informationsseiten im Online-Shop.<\/p>\n<p>6.\u00a0<strong>Streitbeilegung<\/strong><\/p>\n<p>Die Europ\u00e4ische Kommission stellt eine Plattform zur Online-Streitbeilegung (OS) bereit, die Sie hier finden.<br \/>\nZur Teilnahme an einem Streitbeilegungsverfahren vor einer Verbraucherschlichtungsstelle sind wir nicht verpflichtet und nicht bereit.<\/p>\n<p><strong>7.\u00a0Jugendschutz<\/strong><\/p>\n<p>Sofern Ihre Bestellung Waren umfasst, deren Verkauf Altersbeschr\u00e4nkungen unterliegt, stellen wir durch den Einsatz eines zuverl\u00e4ssigen Verfahrens unter Einbeziehung einer pers\u00f6nlichen Identit\u00e4ts- und<br \/>\nAlterspr\u00fcfung sicher, dass der Besteller das erforderliche Mindestalter erreicht hat. Der Zusteller \u00fcbergibt die Ware erst nach erfolgter Alterspr\u00fcfung und nur an den Besteller pers\u00f6nlich.<\/p>\n<p><i><a title=\"AGB\" href=\"https:\/\/shop.trustedshops.com\/de\/rechtstexte\/\" target=\"_blank\" rel=\"noopener\">AGB<\/a> erstellt mit dem <a title=\"Trusted Shops\" href=\"https:\/\/shop.trustedshops.com\/de\/\" target=\"_blank\" rel=\"noopener\">Trusted Shops<\/a> Rechtstexter in Kooperation mit <a title=\"Wilde Beuger Solmecke Rechtsanw\u00e4lte\" href=\"https:\/\/www.wbs-law.de\/\" target=\"_blank\" rel=\"nofollow noopener\">Wilde Beuger Solmecke Rechtsanw\u00e4lte<\/a>.<\/i><\/p>\n<p>unsere Anschrift und Emailadresse:<\/p>\n<p>Familienweingut Kaufmann-Ziegler<br \/>\nInhaber: Walter Ziegler<br \/>\nRhodter Str. 6 + Josef-Meyer-Str. 4<br \/>\n76835 Weyher<br \/>\nTel: 06323\/3255 Fax:06323\/949045<br \/>\nE-Mail: info@weingut-kaufmann-ziegler.de<br \/>\ninfo@weingut-kaufmann-ziegler.de<\/p>\n<p>_<br \/>\n<a name=\"Widerrufsrecht\"><\/a>____________________________________________________________________<\/p>\n<p><strong>Widerrufsbelehrung<\/strong><\/p>\n<p><strong>Widerrufsrecht<\/strong><br \/>\nSie haben das Recht, binnen vierzehn Tagen ohne Angabe von Gr\u00fcnden diesen Vertrag zu widerrufen. Die Widerrufsfrist betr\u00e4gt vierzehn Tage ab dem Tag an dem Sie oder ein von Ihnen benannter Dritter, der nicht der Bef\u00f6rderer ist, die Waren in Besitz genommen haben bzw. hat.<\/p>\n<p>Um Ihr Widerrufsrecht auszu\u00fcben, m\u00fcssen Sie uns<br \/>\nFamilienweingut Kaufmann-Ziegler<br \/>\nInhaber: Walter Ziegler<br \/>\nRhodter Str. 6 + Josef-Meyer-Str. 4<br \/>\n76835 Weyher<br \/>\nTel: 06323\/3255 Fax:06323\/949045<br \/>\nE-Mail: info@weingut-kaufmann-ziegler.de<br \/>\ninfo@weingut-kaufmann-ziegler.de<\/p>\n<p>mittels einer eindeutigen Erkl\u00e4rung (z. B. ein mit der Post versandter Brief, Telefax oder E-Mail) \u00fcber Ihren Entschluss, diesen Vertrag zu widerrufen, informieren. Sie k\u00f6nnen daf\u00fcr das beigef\u00fcgte Muster-Widerrufsformular verwenden, das jedoch nicht vorgeschrieben ist.<\/p>\n<p>Zur Wahrung der Widerrufsfrist reicht es aus, dass Sie die Mitteilung \u00fcber die Aus\u00fcbung des Widerrufsrechts vor Ablauf der Widerrufsfrist absenden.<\/p>\n<p><strong>Folgen des Widerrufs <\/strong><\/p>\n<p>Wenn Sie diesen Vertrag widerrufen, haben wir Ihnen alle Zahlungen, die wir von Ihnen erhalten haben, einschlie\u00dflich der Lieferkosten (mit Ausnahme der zus\u00e4tzlichen Kosten, die sich daraus ergeben, dass Sie eine andere Art der Lieferung als die von uns angebotene, g\u00fcnstigste Standardlieferung gew\u00e4hlt haben), unverz\u00fcglich und sp\u00e4testens binnen vierzehn Tagen ab dem Tag zur\u00fcckzuzahlen, an dem die Mitteilung \u00fcber Ihren Widerruf dieses Vertrags bei uns eingegangen ist. F\u00fcr diese R\u00fcckzahlung verwenden wir dasselbe Zahlungsmittel, das Sie bei der urspr\u00fcnglichen Transaktion eingesetzt haben, es sei denn, mit Ihnen wurde ausdr\u00fccklich etwas anderes vereinbart; in keinem Fall werden Ihnen wegen dieser R\u00fcckzahlung Entgelte berechnet.<br \/>\nWir k\u00f6nnen die R\u00fcckzahlung verweigern, bis wir die Waren wieder zur\u00fcckerhalten haben oder bis Sie den Nachweis erbracht haben, dass Sie die Waren zur\u00fcckgesandt haben, je nachdem, welches der fr\u00fchere Zeitpunkt ist.<\/p>\n<p>Sie haben die Waren unverz\u00fcglich und in jedem Fall sp\u00e4testens binnen vierzehn Tagen ab dem Tag, an dem Sie uns \u00fcber den Widerruf dieses Vertrags unterrichten, an uns zur\u00fcckzusenden oder zu \u00fcbergeben. Die Frist ist gewahrt, wenn Sie die Waren vor Ablauf der Frist von vierzehn Tagen absenden.<br \/>\nSie tragen die unmittelbaren Kosten der R\u00fccksendung der Waren.<br \/>\nSie m\u00fcssen f\u00fcr einen etwaigen Wertverlust der Waren nur aufkommen, wenn dieser Wertverlust auf einen zur Pr\u00fcfung der Beschaffenheit, Eigenschaften und Funktionsweise der Waren nicht notwendigen Umgang mit ihnen zur\u00fcckzuf\u00fchren ist.<\/p>\n<table style=\"width: 100%;\" border=\"1\" cellspacing=\"1\" cellpadding=\"1\">\n<tbody>\n<tr>\n<td><strong>Muster-Widerrufsformular<\/strong><em>(Wenn Sie den Vertrag widerrufen wollen, dann f\u00fcllen Sie bitte dieses Formular aus und senden Sie es zur\u00fcck.)<\/em>\u2013 An Familienweingut Kaufmann-Ziegler<br \/>\nInhaber: Walter Ziegler<br \/>\nRhodter Str. 6 + Josef-Meyer-Str. 4<br \/>\n76835 Weyher<br \/>\nTel: 06323\/3255 Fax:06323\/949045<br \/>\nE-Mail: info@weingut-kaufmann-ziegler.de<br \/>\ninfo@weingut-kaufmann-ziegler.de<\/p>\n<p>\u2013 Hiermit widerrufe(n) ich\/wir (*) den von mir\/uns (*) abgeschlossenen Vertrag \u00fcber den Kauf der folgenden<br \/>\nWaren (*)\/die Erbringung der folgenden Dienstleistung (*)<\/p>\n<p>\u2013 Bestellt am (*)\/erhalten am (*)<\/p>\n<p>\u2013 Name des\/der Verbraucher(s)<\/p>\n<p>\u2013 Anschrift des\/der Verbraucher(s)<\/p>\n<p>\u2013 Unterschrift des\/der Verbraucher(s) (nur bei Mitteilung auf Papier)<\/p>\n<p>\u2013 Datum<\/p>\n<p><em>(*) Unzutreffendes streichen.<\/em><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><i><a title=\"Widerrufsbelehrung\" href=\"https:\/\/shop.trustedshops.com\/de\/rechtstexte\/\" target=\"_blank\" rel=\"noopener\">Widerrufsbelehrung<\/a> erstellt mit dem <a title=\"Trusted Shops\" href=\"https:\/\/shop.trustedshops.com\/de\/\" target=\"_blank\" rel=\"noopener\">Trusted Shops<\/a> Rechtstexter in Kooperation mit <a title=\"Wilde Beuger Solmecke Rechtsanw\u00e4lte\" href=\"https:\/\/www.wbs-law.de\/\" target=\"_blank\" rel=\"nofollow noopener\">Wilde Beuger Solmecke Rechtsanw\u00e4lte<\/a>.<\/i><\/p>\n","protected":false},"excerpt":{"rendered":"<p>IMPRESSUM Weingut Kaufmann-Ziegler Inhaber: Walter Ziegler Rhodter Str. 6 + Josef-Meyer-Str. 4 76835 Weyher Tel: 06323\/3255 Fax:06323\/949045 E-Mail: info@weingut-kaufmann-ziegler.de Steuernr: 24\/232\/00322 Finanzamt Landau i. d. Pfalz Unsere Aufsichtsbeh\u00f6rde ist: Ministerium f\u00fcr Umwelt, Landwirtschaft, Ern\u00e4hrung, Weinbau und Forsten, Kaiser-Friedrich-Str. 1, 55116 Mainz. Wir geh\u00f6ren der Landwirtschaftskammer Rheinland-Pfalz, Rheinland-Pfalz, Burgenlandstr. 7, 55543 Bad Kreuznach an. Gesetzliche Grundlage [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-8","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/weingut-kaufmann-ziegler.de\/catalog\/wp-json\/wp\/v2\/pages\/8","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/weingut-kaufmann-ziegler.de\/catalog\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/weingut-kaufmann-ziegler.de\/catalog\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/weingut-kaufmann-ziegler.de\/catalog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/weingut-kaufmann-ziegler.de\/catalog\/wp-json\/wp\/v2\/comments?post=8"}],"version-history":[{"count":6,"href":"https:\/\/weingut-kaufmann-ziegler.de\/catalog\/wp-json\/wp\/v2\/pages\/8\/revisions"}],"predecessor-version":[{"id":27987,"href":"https:\/\/weingut-kaufmann-ziegler.de\/catalog\/wp-json\/wp\/v2\/pages\/8\/revisions\/27987"}],"wp:attachment":[{"href":"https:\/\/weingut-kaufmann-ziegler.de\/catalog\/wp-json\/wp\/v2\/media?parent=8"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}